{"id":21036,"date":"2025-03-13T12:05:03","date_gmt":"2025-03-13T10:05:03","guid":{"rendered":"https:\/\/www.corredormato.com\/promocion-cal-federal-en-calonge\/"},"modified":"2026-02-25T16:11:21","modified_gmt":"2026-02-25T14:11:21","slug":"promocion-cal-federal-en-calonge","status":"publish","type":"page","link":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/","title":{"rendered":"Promoci\u00f3n: Cal Federal en Calonge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21036\" class=\"elementor elementor-21036 elementor-21007\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cae072 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cae072\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7820793\" data-id=\"7820793\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87e1d56 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"87e1d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"87e1d56\" data-elementor-lightbox-title=\"Promoci\u00f3n Cal Federal en Calonge\" data-elementor-lightbox-description=\"Promoci\u00f3n Cal Federal en Calonge\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjEwMTgsInVybCI6Imh0dHBzOlwvXC93d3cuY29ycmVkb3JtYXRvLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDNcL2NhbC1mZWRlcmFsLmpwZyIsInNsaWRlc2hvdyI6Ijg3ZTFkNTYifQ%3D%3D\" href=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2025\/03\/cal-federal.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/elementor\/thumbs\/cal-federal-r2sky5nms0535ll3mnmlq4m5r29x0esvoxti683nly.jpg\" alt=\"Promoci\u00f3n Cal Federal en Calonge\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b0c6cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b0c6cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2eb3c8\" data-id=\"a2eb3c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a65a8e elementor-widget elementor-widget-heading\" data-id=\"9a65a8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CAL FEDERAL - CALONGE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cd24a3 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9cd24a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">OBRA NUEVA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-sun\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">OBRAS INICIADAS<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">LIBRE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d1fe9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d1fe9d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5351895\" data-id=\"5351895\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c62c059 elementor-widget elementor-widget-google_maps\" data-id=\"c62c059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyCbBGtIfK7odhSioGes5cNqBq89A3p_5dk&#038;q=Calonge%2C%20Espa%C3%B1a&#038;zoom=14\"\n\t\t\t\t\ttitle=\"Calonge, Espa\u00f1a\"\n\t\t\t\t\taria-label=\"Calonge, Espa\u00f1a\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e47604e elementor-widget elementor-widget-text-editor\" data-id=\"e47604e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tras el \u00e9xito de las dos primeras fases, presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.<\/p>\n<p>Cada casa est\u00e1 pensada para tu comodidad:<\/p>\n<ul>\n<li>4 habitaciones<\/li>\n<li>2 ba\u00f1os completos<\/li>\n<li>Jard\u00edn privado<\/li>\n<li>Plaza de parquing incluida<\/li>\n<\/ul>\n<p>Sin embargo, todo es posible: Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles.<\/p>\n<p>La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.<\/p>\n<p>Ubicadas en una zona tranquila y natural, a s\u00f3lo 5 minutos de la playa, estas viviendas le permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.<\/p>\n<p>\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/p>\n<ul>\n<li>Promociona: <strong>Promociones Molina<\/strong><\/li>\n<li>Comercializa: <strong>Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/strong><\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22734d0 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"22734d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2026\/02\/MEMORIA-ACABATS-CALONGE-2025-ENG.pdf\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Descargar documento de calidades (EN)<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c07929c\" data-id=\"c07929c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8887255 elementor-widget elementor-widget-heading\" data-id=\"8887255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cont\u00e1ctanos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84035f9 elementor-widget elementor-widget-text-editor\" data-id=\"84035f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si desea m\u00e1s informaci\u00f3n sobre esta promoci\u00f3n, por favor, rellene el cuestionario:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56d6d2b elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"56d6d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Siguiente&quot;,&quot;step_previous_label&quot;:&quot;Anterior&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\" Nuevo formulario\" aria-label=\" Nuevo formulario\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"21036\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"56d6d2b\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"21036\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre y apellidos\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nombre y apellidos\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t Correo electr\u00f3nico\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\" Correo electr\u00f3nico\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-telefon elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telefon\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTel\u00e9fono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[telefon]\" id=\"form-field-telefon\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Tel\u00e9fono\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensaje\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensaje\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-privacidad elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-privacidad\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPrivacidad\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[privacidad]\" id=\"form-field-privacidad\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-privacidad\">He le\u00eddo y acepto la <strong><a href=\"https:\/\/www.corredormato.com\/es\/polititica-de-privacidad\/\" target=\"_blank\">pol\u00edtica de privacidad<\/a><\/strong>.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-Promocion elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[Promocion]\" id=\"form-field-Promocion\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" value=\"15\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-recaptcha elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-recaptcha\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6Ldj-cYaAAAAAFiCHo_3Vsw4fgEiBt5_7DRWFifr\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5af73c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5af73c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04e18cd\" data-id=\"04e18cd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b27addd elementor-widget elementor-widget-heading\" data-id=\"b27addd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inmuebles de la promoci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d93ebcd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d93ebcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f35a133 listado-promociones-on elementor-widget elementor-widget-shortcode\" data-id=\"f35a133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"n2r__list \" data-n2r-searchparams=\"\">\n    <div class=\"n2r__row\">\n    <div class=\"n2r__list__items\">\n      <div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27284\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625886-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-45-calonge-27284\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2723<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 142 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaEn este caso se trata de la vivienda esquinera y cuenta con 77.75 m\u00b2 de jard\u00edn privado.Comprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">465.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-45-calonge-27284\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27285\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625909-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-44-calonge-27285\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2722<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">450.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-44-calonge-27285\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27287\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625955-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-42-calonge-27287\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2720<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">450.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-42-calonge-27287\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27286\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27286\/625932-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-43-calonge-27286\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2721<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">435.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-43-calonge-27286\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27288\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27288\/625978-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-41-calonge-27288\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2719<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">435.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-41-calonge-27288\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27289\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27289\/626002-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-40-calonge-27289\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2718<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">435.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-40-calonge-27289\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27290\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27290\/626034-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-39-calonge-27290\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2717<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">435.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-39-calonge-27290\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27291\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27291\/626057-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-38-calonge-27291\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2716<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 142 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaEn este caso se trata de la vivienda esquinera y cuenta con 192,46 m\u00b2 de jard\u00edn privado.Comprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles. La entrega est\u00e1 prevista para el tercer trimestre de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">490.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-38-calonge-27291\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable n2r__list__item--rented  \" data-id=\"24005\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--sold\">Vendido<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/24005\/551988-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-64-calonge-24005\/\">7 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2467<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 130 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Tu nuevo hogar en la Costa Brava est\u00e1 m\u00e1s cerca que nunca! Con las OBRAS INICIADAS, esta exclusiva promoci\u00f3n en Calonge ofrece 7 casas de obra nueva en una primera fase que avanza con firmeza. Cada vivienda cuenta con 4 habitaciones, 2 ba\u00f1os, jard\u00edn privado y plaza de parking, pensado para ofrecerte el m\u00e1ximo confort y calidad de vida.La entrega est\u00e1 prevista para el primer trimestre de 2026, lo que te brinda tiempo para planificar con tranquilidad la mudanza en tu nuevo hogar. Ubicadas en la bonita poblaci\u00f3n de Calonge a tan s\u00f3lo 5 minutos de la playa, disfrutar\u00e1 de un entorno natural \u00fanico, con la belleza de la Costa Brava a su alcance.\u00a1No pierdas la oportunidad de vivir en un lugar \u00fanico! \u00a1Reserva ahora y empieza a imaginar tu futuro en esta hermosa casa!Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">410.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-64-calonge-24005\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26454\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26454\/595882-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-60-calonge-26454\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2631<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">432.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-60-calonge-26454\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26453\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26453\/595848-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-59-calonge-26453\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2630<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase (7 casas vendidas y en construcci\u00f3n con entrega en 2026), presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">425.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-59-calonge-26453\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable n2r__list__item--rented  \" data-id=\"24055\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--sold\">Vendido<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/24055\/552734-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-66-calonge-24055\/\">7 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING A 5 MINUTOS DE LA PLAYA<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2470<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 130 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Tu nuevo hogar en la Costa Brava est\u00e1 m\u00e1s cerca que nunca! Con las OBRAS INICIADAS, esta exclusiva promoci\u00f3n en Calonge ofrece 7 casas de obra nueva en una primera fase que avanza con firmeza. Cada vivienda cuenta con 4 habitaciones, 2 ba\u00f1os, jard\u00edn privado y plaza de parking, pensado para ofrecerte el m\u00e1ximo confort y calidad de vida.La entrega est\u00e1 prevista para el primer trimestre de 2026, lo que te brinda tiempo para planificar con tranquilidad la mudanza en tu nuevo hogar. Ubicadas en la bonita poblaci\u00f3n de Calonge a tan s\u00f3lo 5 minutos de la playa, disfrutar\u00e1 de un entorno natural \u00fanico, con la belleza de la Costa Brava a su alcance.\u00a1No pierdas la oportunidad de vivir en un lugar \u00fanico! \u00a1Reserva ahora y empieza a imaginar tu futuro en esta hermosa casa!Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">410.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-66-calonge-24055\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable n2r__list__item--rented  \" data-id=\"24058\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--sold\">Vendido<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/24058\/552840-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-67-calonge-24058\/\">7 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2463<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 130 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Tu nuevo hogar en la Costa Brava est\u00e1 m\u00e1s cerca que nunca! Con la OBRAS INICIADAS, esta exclusiva promoci\u00f3n en Calonge ofrece 7 casas de obra nueva en una primera fase que avanza a paso firme. Cada vivienda cuenta con 4 habitaciones, 2 ba\u00f1os, jard\u00edn privado y plaza de parking, todo pensado para ofrecerte el m\u00e1ximo confort y calidad de vida.\nLa entrega est\u00e1 prevista para el primer trimestre de 2026, lo que te brinda tiempo para planificar con tranquilidad la mudanza a tu nuevo hogar. Ubicadas en la hermosa poblaci\u00f3n de Calonge a tan solo 5 minutos de la playa, disfrutar\u00e1s de un entorno natural \u00fanico, con la belleza de la Costa Brava a tu alcance.\n\u00a1No pierdas la oportunidad de vivir en un lugar \u00fanico! Reserva ahora y empieza a imaginar tu futuro en esta hermosa casa!\nPromociona: Promociones Molina\nComercializa: Corredor Mat\u00f3 &amp; Urbenia Serveis Immobiliaris\n<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">425.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-67-calonge-24058\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26459\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26459\/616905-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-55-calonge-26459\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2635<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"3 aseos\"><i class=\"n2r_toilet\"><\/i> 3<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscina\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!\nTras el \u00e9xito de la primera fase, presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.\nCada casa est\u00e1 pensada para tu comodidad; En este caso esta tiene:&nbsp;4 habitaciones\n3 ba\u00f1os completos\nJard\u00edn privado\nPlaza de parking incluidaPiscina&nbsp;Comprar sobre plano te permite personalizar la vivienda a tu gusto.\n\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?\nTodo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles.\nLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.\nUbicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.\n\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.\nPromociona: Promociones Molina\nComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">483.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-55-calonge-26459\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26461\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--offer\">Oferta<\/span><span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26461\/596504-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-57-calonge-26461\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2633<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase, presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?Todo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles.La entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\"><span class=\"n2r__list__item__price__amount n2r__list__item__price__old\">455.000 \u20ac<\/span> 425.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-57-calonge-26461\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26460\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26460\/596471-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-56-calonge-26460\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2634<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"5 habitaciones\"><i class=\"n2r_room\"><\/i> 5<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"3 aseos\"><i class=\"n2r_toilet\"><\/i> 3<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!\nTras el \u00e9xito de la primera fase, presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.\nCada casa est\u00e1 pensada para tu comodidad. En este caso, esta casa consta de:5 habitaciones\n3 ba\u00f1os completos\nJard\u00edn privado\nPlaza de parking incluidaComprar sobre plano te permite personalizar la vivienda a tu gusto.\n\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?\nTodo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles.\nLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.\nUbicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.\n\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.\nPromociona: Promociones Molina\nComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">453.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-56-calonge-26460\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26458\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26458\/596403-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-54-calonge-26458\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2636<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!\nTras el \u00e9xito de la primera fase, presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.\nCada casa est\u00e1 pensada para tu comodidad:\n4 habitaciones\n2 ba\u00f1os completos\nJard\u00edn privado\nPlaza de parking incluida\nComprar sobre plano te permite personalizar la vivienda a tu gusto.\n\u00bfPrefieres las cuatro habitaciones en la planta superior y ampliar toda la zona de d\u00eda en la planta baja? \u00bfQuieres dos ba\u00f1os en la parte superior? \u00bfUna piscina en tu jard\u00edn?\nTodo es posible. Cons\u00faltanos para m\u00e1s informaci\u00f3n y descubre todas las opciones de personalizaci\u00f3n disponibles.\nLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.\nUbicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.\n\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.\nPromociona: Promociones Molina\nComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">425.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-54-calonge-26458\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26462\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26462\/596538-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-58-calonge-26462\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2632<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase, presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">425.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-58-calonge-26462\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"26457\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/26457\/596369-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-53-calonge-26457\/\">8 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING EN CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2637<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Nueva fase a la venta en Calonge!Tras el \u00e9xito de la primera fase, presentamos la segunda fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado.Cada casa est\u00e1 pensada para tu comodidad:4 habitaciones2 ba\u00f1os completosJard\u00edn privadoPlaza de parking incluidaLa entrega est\u00e1 prevista para principios de 2027, ofreci\u00e9ndote tiempo suficiente para planificar tu mudanza y personalizar tu nuevo hogar.Ubicadas en una zona tranquila y natural, a solo 5 minutos de la playa, estas viviendas te permitir\u00e1n disfrutar de todo el encanto de la Costa Brava.Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios\u00a1No pierdas tu oportunidad! Reserva ahora en esta segunda fase y asegura tu casa en Calonge junto al mar.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">432.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-53-calonge-26457\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable n2r__list__item--rented  \" data-id=\"24057\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--sold\">Vendido<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/24057\/552805-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-64-calonge-24057\/\">7 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING A 5 MINUTOS DE LA PLAYA<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2468<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 130 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Tu nuevo hogar en la Costa Brava est\u00e1 m\u00e1s cerca que nunca! Con las OBRAS INICIADAS, esta exclusiva promoci\u00f3n en Calonge ofrece 7 casas de obra nueva en una primera fase que avanza con firmeza. Cada vivienda cuenta con 4 habitaciones, 2 ba\u00f1os, jard\u00edn privado y plaza de parking, pensado para ofrecerte el m\u00e1ximo confort y calidad de vida.La entrega est\u00e1 prevista para el primer trimestre de 2026, lo que te brinda tiempo para planificar con tranquilidad la mudanza en tu nuevo hogar. Ubicadas en la bonita poblaci\u00f3n de Calonge a tan s\u00f3lo 5 minutos de la playa, disfrutar\u00e1 de un entorno natural \u00fanico, con la belleza de la Costa Brava a su alcance.\u00a1No pierdas la oportunidad de vivir en un lugar \u00fanico! \u00a1Reserva ahora y empieza a imaginar tu futuro en esta hermosa casa!Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">410.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-64-calonge-24057\/\">M\u00e1s detalles<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"24056\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">Reservado<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/24056\/552770-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-65-calonge-24056\/\">7 CASAS DE OBRA NUEVA CON JARD\u00cdN Y PARKING A 5 MINUTOS DE LA PLAYA<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2469<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 habitaciones\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 aseos\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"Metros de la propiedad\"><i class=\"n2r_property_meters\"><\/i> 130 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00a1Tu nuevo hogar en la Costa Brava est\u00e1 m\u00e1s cerca que nunca! Con las OBRAS INICIADAS, esta exclusiva promoci\u00f3n en Calonge ofrece 7 casas de obra nueva en una primera fase que avanza con firmeza. Cada vivienda cuenta con 4 habitaciones, 2 ba\u00f1os, jard\u00edn privado y plaza de parking, pensado para ofrecerte el m\u00e1ximo confort y calidad de vida.La entrega est\u00e1 prevista para el primer trimestre de 2026, lo que te brinda tiempo para planificar con tranquilidad la mudanza en tu nuevo hogar. Ubicadas en la bonita poblaci\u00f3n de Calonge a tan s\u00f3lo 5 minutos de la playa, disfrutar\u00e1 de un entorno natural \u00fanico, con la belleza de la Costa Brava a su alcance.\u00a1No pierdas la oportunidad de vivir en un lugar \u00fanico! \u00a1Reserva ahora y empieza a imaginar tu futuro en esta hermosa casa!Promociona: Promociones MolinaComercializa: Corredor Mat\u00f3 &amp; Urbenia Servicios Inmobiliarios<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">410.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/es\/venta\/venta-casa-adosada-cal-federal-casa-65-calonge-24056\/\">M\u00e1s detalles<\/a>\n  <\/div>    <\/div>\n      <\/div>\n  <div class=\"n2r__pagination\">\n  <div class=\"n2r__pagination__summary\">\n    21 Resultados    -\n    P\u00e1gina 1 de 1  <\/div>\n  <div class=\"separator\"><\/div>\n  <\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CAL FEDERAL &#8211; CALONGE OBRA NUEVA OBRAS INICIADAS LIBRE Tras el \u00e9xito de las dos primeras fases, presentamos la tercera fase de esta promoci\u00f3n exclusiva en Calonge: 8 nuevas viviendas de obra nueva que mantienen el mismo dise\u00f1o y calidad que tanto inter\u00e9s han despertado. Cada casa est\u00e1 pensada para tu comodidad: 4 habitaciones 2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13639,"parent":6464,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-21036","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management<\/title>\n<meta name=\"description\" content=\"Pensem en les vostres vacances, oferint-vos el m\u00e9s gran ventall d\u2019immobles i serveis, per satisfer totes les vostres peticions. Si sou propietaris i voleu llogar, Corredor Mat\u00f3 \u00e9s la vostra ag\u00e8ncia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management\" \/>\n<meta property=\"og:description\" content=\"Pensem en les vostres vacances, oferint-vos el m\u00e9s gran ventall d\u2019immobles i serveis, per satisfer totes les vostres peticions. Si sou propietaris i voleu llogar, Corredor Mat\u00f3 \u00e9s la vostra ag\u00e8ncia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/\" \/>\n<meta property=\"og:site_name\" content=\"Corredor Mat\u00f3 Real Estate &amp; Property Management\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T14:11:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2024\/02\/RRSS_Corredor_MATO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/\",\"name\":\"Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.corredormato.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/RRSS_Corredor_MATO.jpg\",\"datePublished\":\"2025-03-13T10:05:03+00:00\",\"dateModified\":\"2026-02-25T14:11:21+00:00\",\"description\":\"Pensem en les vostres vacances, oferint-vos el m\u00e9s gran ventall d\u2019immobles i serveis, per satisfer totes les vostres peticions. Si sou propietaris i voleu llogar, Corredor Mat\u00f3 \u00e9s la vostra ag\u00e8ncia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nueva\\\/promocion-cal-federal-en-calonge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obra nueva\",\"item\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/obra-nova\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Promoci\u00f3n: Cal Federal en Calonge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/\",\"name\":\"Corredor Mat\u00f3 Real Estate &amp; Property Management\",\"description\":\"Real Estate &amp; Property Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/#organization\"},\"alternateName\":\"Corredor Mat\u00f3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.corredormato.com\\\/resultats-de-cerca-lloguer\\\/?search_text={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/#organization\",\"name\":\"Corredor Mat\u00f3 | Real Estate & Property Management\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.corredormato.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.png\",\"width\":970,\"height\":225,\"caption\":\"Corredor Mat\u00f3 | Real Estate & Property Management\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management","description":"Pensem en les vostres vacances, oferint-vos el m\u00e9s gran ventall d\u2019immobles i serveis, per satisfer totes les vostres peticions. Si sou propietaris i voleu llogar, Corredor Mat\u00f3 \u00e9s la vostra ag\u00e8ncia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/","og_locale":"es_ES","og_type":"article","og_title":"Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management","og_description":"Pensem en les vostres vacances, oferint-vos el m\u00e9s gran ventall d\u2019immobles i serveis, per satisfer totes les vostres peticions. Si sou propietaris i voleu llogar, Corredor Mat\u00f3 \u00e9s la vostra ag\u00e8ncia.","og_url":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/","og_site_name":"Corredor Mat\u00f3 Real Estate &amp; Property Management","article_modified_time":"2026-02-25T14:11:21+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2024\/02\/RRSS_Corredor_MATO.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/","url":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/","name":"Promoci\u00f3n: Cal Federal en Calonge - Corredor Mat\u00f3 Real Estate &amp; Property Management","isPartOf":{"@id":"https:\/\/www.corredormato.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/#primaryimage"},"image":{"@id":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/#primaryimage"},"thumbnailUrl":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2024\/02\/RRSS_Corredor_MATO.jpg","datePublished":"2025-03-13T10:05:03+00:00","dateModified":"2026-02-25T14:11:21+00:00","description":"Pensem en les vostres vacances, oferint-vos el m\u00e9s gran ventall d\u2019immobles i serveis, per satisfer totes les vostres peticions. Si sou propietaris i voleu llogar, Corredor Mat\u00f3 \u00e9s la vostra ag\u00e8ncia.","breadcrumb":{"@id":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.corredormato.com\/es\/obra-nueva\/promocion-cal-federal-en-calonge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.corredormato.com\/es\/"},{"@type":"ListItem","position":2,"name":"Obra nueva","item":"https:\/\/www.corredormato.com\/es\/obra-nova\/"},{"@type":"ListItem","position":3,"name":"Promoci\u00f3n: Cal Federal en Calonge"}]},{"@type":"WebSite","@id":"https:\/\/www.corredormato.com\/es\/#website","url":"https:\/\/www.corredormato.com\/es\/","name":"Corredor Mat\u00f3 Real Estate &amp; Property Management","description":"Real Estate &amp; Property Management","publisher":{"@id":"https:\/\/www.corredormato.com\/es\/#organization"},"alternateName":"Corredor Mat\u00f3","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.corredormato.com\/resultats-de-cerca-lloguer\/?search_text={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.corredormato.com\/es\/#organization","name":"Corredor Mat\u00f3 | Real Estate & Property Management","url":"https:\/\/www.corredormato.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.corredormato.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2021\/04\/logo.png","contentUrl":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2021\/04\/logo.png","width":970,"height":225,"caption":"Corredor Mat\u00f3 | Real Estate & Property Management"},"image":{"@id":"https:\/\/www.corredormato.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/pages\/21036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/comments?post=21036"}],"version-history":[{"count":13,"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/pages\/21036\/revisions"}],"predecessor-version":[{"id":22927,"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/pages\/21036\/revisions\/22927"}],"up":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/pages\/6464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/media\/13639"}],"wp:attachment":[{"href":"https:\/\/www.corredormato.com\/es\/wp-json\/wp\/v2\/media?parent=21036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}