{"id":8341,"date":"2023-10-02T11:11:52","date_gmt":"2023-10-02T09:11:52","guid":{"rendered":"http:\/\/52.30.243.130\/vente-costa-braqva\/maisons\/"},"modified":"2024-02-29T17:05:55","modified_gmt":"2024-02-29T15:05:55","slug":"maisons","status":"publish","type":"page","link":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/","title":{"rendered":"Maisons \u00e0 vendre sur la Costa Brava"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8341\" class=\"elementor elementor-8341 elementor-8219\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1b0c29 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f1b0c29\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d6532e\" data-id=\"3d6532e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6363595 listado-general elementor-widget elementor-widget-shortcode\" data-id=\"6363595\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"listado-general-venta\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"n2r__list grid\" data-n2r-searchparams=\"\">\n      <div class=\"n2r__list__header\">\n              <a href=\"#\" class=\"n2r__btn n2r__btn--mobileicon n2r__btn--filters\" data-toggleclass=\"filters\" data-target-parent=\".n2r__list\">Ouvrez les filtres<\/a>\n            <select name=\"orderby\" class=\"n2r__select\" aria-label=\"Trier les r\u00e9sultats\">\n        <option value=\"\/fr\/wp-json\/wp\/v2\/pages\/8341?orderby=\"> Trier les r\u00e9sultats<\/option>\n        <option value=\"\/fr\/wp-json\/wp\/v2\/pages\/8341?orderby=pricedesc\" > Prix: de haut en bas        <option value=\"\/fr\/wp-json\/wp\/v2\/pages\/8341?orderby=priceasc\" > Prix: de bas en haut      <\/select>\n      <span class=\"separator\"><\/span>\n              <a href=\"\" class=\"n2r__btn n2r__btn--mobileicon n2r__btn--map\" data-toggleclass=\"map\" data-target-parent=\".n2r__list\" data-activated-text=\"Masquer la carte\" data-deactivated-text=\"Montrer la carte\">Montrer la carte<\/a>\n                  <a href=\"#\" class=\"n2r__btn n2r__btn--mobileicon n2r__btn--searchinmap\">recherche sur la carte<\/a>\n            <div class=\"n2r__btngroup n2r__btngroup--viewmode\">\n        <a href=\"\" class=\"n2r__btn n2r__btn--grid active\" data-viewmode=\"grid\" aria-label=\"Grid view\"><\/a>\n        <a href=\"\" class=\"n2r__btn n2r__btn--list \" data-viewmode=\"list\" aria-label=\"List view\"><\/a>\n      <\/div>\n    <\/div>\n  <div class=\"n2r__list__filters\">\n  <header>\n    Filtrer recherche    <a href=\"#\" class=\"n2r__btn--close\" data-toggleclass=\"filters\" data-target-parent=\".n2r__list\" aria-label=\"Fermer\"><\/a>\n  <\/header>\n  <form method=\"get\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/8341?_f=1\" role=\"form\" autocomplete=\"off\">\n    <input type=\"hidden\" aria-hidden=\"true\" name=\"commercialization_type\" value=\"sale\">\n\n                <div class=\"n2r__list__filters__field\">\n              <label for=\"n2r-filters-search-text-56646\">Chercher<\/label>\n              <input type=\"text\" name=\"search_text\" id=\"n2r-filters-search-text-56646\" class=\"n2r__input\" value=\"\">\n            <\/div>\n                          <div class=\"n2r__list__filters__field\">\n                <label for=\"n2r-filters-city-56646\">Ville<\/label>\n                <select name=\"city\" id=\"n2r-filters-city-56646\" class=\"n2r__select\">\n                  <option value=\"\">Tout<\/option>\n                  <option value=\"Arenys De Mar\" >Arenys De Mar<\/option><option value=\"Arenys de Munt\" >Arenys de Munt<\/option><option value=\"Argentona\" >Argentona<\/option><option value=\"Barcelona\" >Barcelona<\/option><option value=\"Begur\" >Begur<\/option><option value=\"Cabrils\" >Cabrils<\/option><option value=\"Caldes d&#039;Estrac\" >Caldes d&#039;Estrac<\/option><option value=\"Calella De Palafrugell\" >Calella De Palafrugell<\/option><option value=\"Calonge\" >Calonge<\/option><option value=\"Canet De Mar\" >Canet De Mar<\/option><option value=\"Castell-Platja d&#039;Aro\" >Castell-Platja d&#039;Aro<\/option><option value=\"Cru\u00eflles, Monells i Sant Sadurn\u00ed de l&#039;Heura\" >Cru\u00eflles, Monells i Sant Sadurn\u00ed de l&#039;Heura<\/option><option value=\"El Masnou\" >El Masnou<\/option><option value=\"Esplugues de Llobregat\" >Esplugues de Llobregat<\/option><option value=\"Forallac\" >Forallac<\/option><option value=\"L&#039; Ametlla Del Valles\" >L&#039; Ametlla Del Valles<\/option><option value=\"L&#039;Escala\" >L&#039;Escala<\/option><option value=\"La Garriga\" >La Garriga<\/option><option value=\"Llafranc\" >Llafranc<\/option><option value=\"Matar\u00f3\" >Matar\u00f3<\/option><option value=\"Mont-Ras\" >Mont-Ras<\/option><option value=\"Palafrugell\" >Palafrugell<\/option><option value=\"Palam\u00f3s\" >Palam\u00f3s<\/option><option value=\"Pals\" >Pals<\/option><option value=\"Platja D&#039;Aro\" >Platja D&#039;Aro<\/option><option value=\"Premi\u00e0 de Dalt\" >Premi\u00e0 de Dalt<\/option><option value=\"Premi\u00e1 de Mar\" >Premi\u00e1 de Mar<\/option><option value=\"S&#039;Agar\u00f3\" >S&#039;Agar\u00f3<\/option><option value=\"Sant Andreu de Llavaneres\" >Sant Andreu de Llavaneres<\/option><option value=\"Sant Antoni De Calonge\" >Sant Antoni De Calonge<\/option><option value=\"Sant Cugat del Vall\u00e8s\" >Sant Cugat del Vall\u00e8s<\/option><option value=\"Sant Feliu de Gu\u00edxols\" >Sant Feliu de Gu\u00edxols<\/option><option value=\"Sant Gregori\" >Sant Gregori<\/option><option value=\"Sant Pol De Mar\" >Sant Pol De Mar<\/option><option value=\"Sant Vicen\u00e7 de Montalt\" >Sant Vicen\u00e7 de Montalt<\/option><option value=\"Santa Cristina D&#039;Aro\" >Santa Cristina D&#039;Aro<\/option><option value=\"Sitges\" >Sitges<\/option><option value=\"Tagamanent\" >Tagamanent<\/option><option value=\"Tamariu\" >Tamariu<\/option><option value=\"Tei\u00e0\" >Tei\u00e0<\/option><option value=\"Vilassar de Mar\" >Vilassar de Mar<\/option>                <\/select>\n              <\/div>\n                          <div class=\"n2r__list__filters__field\">\n                <label for=\"n2r-filters-zone-56646\">Zone<\/label>\n                <select name=\"zone\" id=\"n2r-filters-zone-56646\" class=\"n2r__select\" data-remoteurl=\"https:\/\/www.corredormato.com\/wp-json\/n2r\/v1\/zones\">\n                  <option value=\"\">Tout<\/option>\n                  <option value=\"Barcelona\" >Barcelona<\/option><option value=\"Costa Brava\" >Costa Brava<\/option><option value=\"Maresme\" >Maresme<\/option>                <\/select>\n              <\/div>\n                          <div class=\"n2r__list__filters__field \">\n                <label for=\"n2r-filters-type-56646\">Type de propri\u00e9t\u00e9<\/label>\n                <select name=\"type\" id=\"n2r-filters-type-56646\" class=\"n2r__select\">\n                  <option value=\"\">Type de propri\u00e9t\u00e9<\/option>\n                  <option value=\"apartment\" >Appartement<\/option><option value=\"attached_house\" >Maison jumel\u00e9e<\/option><option value=\"commercial_space\" >Espace commercial<\/option><option value=\"flat\" >Appartement<\/option><option value=\"isolated_house\" >Villa priv\u00e9e \/ Villa<\/option><option value=\"masia\" >Masia<\/option><option value=\"penthouse\" >Attique<\/option><option value=\"terrain\" >Terrain<\/option>                <\/select>\n              <\/div>\n                          <div class=\"n2r__list__filters__field\">\n                <label for=\"n2r-filters-category-56646\" Cat\u00e9gorie<\/label>\n                  <select name=\"category\" id=\"n2r-filters-category-56646\" class=\"n2r__select\">\n                    <option value=\"\">Tout<\/option>\n                    <option value=\"11\" >Exclusif<\/option><option value=\"12\" >Premium<\/option><option value=\"368\" >vip<\/option><option value=\"417\" >Nouvelle construction<\/option><option value=\"437\" >Maisons de luxe sur la Costa Brava<\/option><option value=\"438\" >Maisons avec vue sur la mer sur la Costa Brava<\/option><option value=\"451\" >PROMO-SA-RODA<\/option><option value=\"476\" >Nouvelle construction sans d\u00e9veloppement<\/option><option value=\"499\" >Baix Empord\u00e0<\/option><option value=\"502\" >PROMO CAL FEDERAL<\/option><option value=\"514\" >PROMO-FLOR-SARDENYA<\/option><option value=\"573\" >PROMO Els Pins d\u2019Arenys<\/option><option value=\"578\" >PROMO VALL D&#039;ARO RESIDENCIAL<\/option><option value=\"635\" >PROMO-CAN-GUITART<\/option>                  <\/select>\n              <\/div>\n                        <div class=\"n2r__list__filters__field\">\n              <label for=\"n2r-filters-rooms-min-56646\">Chambres<\/label>\n              <div class=\"n2r__radio\">\n                <input type=\"hidden\" aria-hidden=\"true\" name=\"min_room_number\" id=\"n2r-filters-rooms-min-56646\" value=\"\">\n                                  <div class=\"n2r__radio__item \" data-value=\"1\">+1<\/div>\n                                  <div class=\"n2r__radio__item \" data-value=\"2\">+2<\/div>\n                                  <div class=\"n2r__radio__item \" data-value=\"3\">+3<\/div>\n                                  <div class=\"n2r__radio__item \" data-value=\"4\">+4<\/div>\n                                  <div class=\"n2r__radio__item \" data-value=\"5\">+5<\/div>\n                              <\/div>\n            <\/div>\n                      <div class=\"n2r__list__filters__field\">\n              <label for=\"n2r-filters-toilets-min-56646\">Toilettes<\/label>\n              <div class=\"n2r__radio\">\n                <input type=\"hidden\" id=\"n2r-filters-toilets-min-56646\" aria-hidden=\"true\" name=\"min_toilets_number\" value=\"\">\n                                  <div class=\"n2r__radio__item \" data-value=\"1\">+1<\/div>\n                                  <div class=\"n2r__radio__item \" data-value=\"2\">+2<\/div>\n                                  <div class=\"n2r__radio__item \" data-value=\"3\">+3<\/div>\n                              <\/div>\n            <\/div>\n                      <div class=\"n2r__list__filters__field\">\n              <label for=\"n2r-filters-property-meters-min-56646\">Surface au sol<\/label>\n              <select name=\"property_meters_min\" id=\"n2r-filters-property-meters-min-56646\" class=\"n2r__select\">\n                <option value=\"\">Aucune limite<\/option>\n                                  <option value=\"50\" >\n                    50m2                  <\/option>\n                                  <option value=\"60\" >\n                    60m2                  <\/option>\n                                  <option value=\"70\" >\n                    70m2                  <\/option>\n                                  <option value=\"80\" >\n                    80m2                  <\/option>\n                                  <option value=\"90\" >\n                    90m2                  <\/option>\n                                  <option value=\"100\" >\n                    100m2                  <\/option>\n                                  <option value=\"125\" >\n                    125m2                  <\/option>\n                                  <option value=\"150\" >\n                    150m2                  <\/option>\n                                  <option value=\"175\" >\n                    175m2                  <\/option>\n                                  <option value=\"200\" >\n                    200m2                  <\/option>\n                                  <option value=\"250\" >\n                    250m2                  <\/option>\n                                  <option value=\"300\" >\n                    300m2                  <\/option>\n                                  <option value=\"400\" >\n                    400m2                  <\/option>\n                                  <option value=\"500\" >\n                    500m2                  <\/option>\n                              <\/select>\n            <\/div>\n                <div class=\"n2r__list__filters__field\">\n        <label>Plus de fonctionnalit\u00e9s<\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"pets\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"pets\" value=\"1\" >\n            Mascottes          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"lift\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"lift\" value=\"1\" >\n            Ascenseur          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"pool\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"pool\" value=\"1\" >\n            Piscine          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"parking_garage\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"parking_garage\" value=\"1\" >\n            Parking          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"garden\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"garden\" value=\"1\" >\n            Jardin          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"wifi\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"wifi\" value=\"1\" >\n            WIFI          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"air_conditioning\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"air_conditioning\" value=\"1\" >\n            Climatisation          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"barbecue\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"barbecue\" value=\"1\" >\n            Barbecue          <\/label>\n                  <label class=\"n2r__btn n2r__btn--outline n2r__btn--checkbox\">\n            <input type=\"hidden\" aria-hidden=\"true\" name=\"terrace\" value=\"\">\n            <input type=\"checkbox\" class=\"n2r__checkbox\" name=\"terrace\" value=\"1\" >\n            Terrasse          <\/label>\n              <\/div>\n        <footer>\n      <button type=\"submit\" class=\"n2r__btn n2r__btn--search\">Chercher<\/button>\n    <\/footer>\n  <\/form>\n<\/div>  <div class=\"n2r__row\">\n    <div class=\"n2r__list__items\">\n      <div class=\"n2r__list__item n2r__clickable   \" data-id=\"27683\">\n    <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642438-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642439-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642440-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642441-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642442-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642443-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642444-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642445-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642446-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642447-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642448-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642449-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642450-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642451-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642452-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642453-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642466-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642741-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642742-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642743-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642744-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642455-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642456-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642457-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642458-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642459-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642463-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642467-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642471-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642472-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642473-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642474-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/642475-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27683\/645722-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-es-raco-begur-27683\/\">Magnifique maison avec piscine et une vue magnifique sur la mer, \u00e0 seulement 500 m\u00e8tres de la plage<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2729<\/div>\n      <div class=\"n2r__list__item__turisticreference\">WITH TOURIST LICENSE<\/div>      <div class=\"n2r__list__item__city\">Begur<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"3 toilettes\"><i class=\"n2r_toilet\"><\/i> 3<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 190 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Magnifique maison en pierre avec une fantastique piscine priv\u00e9e et de belles vues sur la mer, \u00e0 seulement 500 m\u00e8tres de la plage de Sa Riera.Construite de plain-pied, la maison dispose d&#039;une grande cour en pierre et est entour\u00e9e d&#039;un superbe jardin. La spectaculaire terrasse, avec sa couverture en bois et sa piscine idyllique face \u00e0 la mer, vous permettra de profiter du soleil, de la brise marine et du magnifique paysage m\u00e9diterran\u00e9en. Profitez de ce petit paradis en toute intimit\u00e9 !Grand et lumineux salon-salle \u00e0 manger avec acc\u00e8s \u00e0 la terrasse et vue sur la piscine et la mer, depuis lequel on acc\u00e8de \u00e9galement \u00e0 l&#039;espace barbecue et \u00e0 la jolie cuisine enti\u00e8rement \u00e9quip\u00e9e.La maison dispose de trois chambres : la chambre principale est une superbe suite avec lit double, salle de bain avec douche, splendides vues sur la mer et acc\u00e8s direct \u00e0 la terrasse, ainsi que deux autres chambres, toutes deux avec lit double. De plus, la propri\u00e9t\u00e9 comprend un quatri\u00e8me espace suppl\u00e9mentaire, actuellement am\u00e9nag\u00e9 en chambre, accessible directement depuis la terrasse.En plus de la salle de bain de la suite, la maison dispose de deux autres salles de bain avec douche. Toutes les pi\u00e8ces de la maison sont ext\u00e9rieures et tr\u00e8s lumineuses. Parking pour une voiture.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">1.450.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-es-raco-begur-27683\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"27791\">\n    <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645408-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645409-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645410-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645411-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645412-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645413-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645414-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645415-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645416-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645417-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645418-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645419-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645420-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645421-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645422-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645423-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645424-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645425-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645426-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645427-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645428-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645429-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645430-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645431-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645432-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645433-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645434-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645435-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645436-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27791\/645437-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-homer-llafranc-27791\/\">Maison mitoyenne \u00e0 Llafranc, \u00e0 seulement 500 m\u00e8tres de la plage<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2751<\/div>\n            <div class=\"n2r__list__item__city\">Llafranc<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"5 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 5<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"3 toilettes\"><i class=\"n2r_toilet\"><\/i> 3<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 135 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Maison mitoyenne \u00e0 Llafranc avec jardin privatif et piscine commune, \u00e0 seulement 500 m de la plage\nSuperbe maison de ville de 135 m\u00b2 situ\u00e9e dans une petite copropri\u00e9t\u00e9 de sept voisins, dans l&#039;un des quartiers les plus pris\u00e9s de la Costa Brava : Llafranc. \u00c0 seulement 10 minutes \u00e0 pied de la plage, cette propri\u00e9t\u00e9 est id\u00e9ale comme r\u00e9sidence principale ou secondaire.\nLa maison est r\u00e9partie sur plusieurs niveaux, offrant un confort et une intimit\u00e9 optimaux.&nbsp;Rez-de-chauss\u00e9e : spacieux garage privatif de 45 m\u00b2 avec acc\u00e8s direct \u00e0 la maison et hall d&#039;entr\u00e9e.\nPremier \u00e9tage : lumineux s\u00e9jour-salle \u00e0 manger avec chemin\u00e9e et acc\u00e8s \u00e0 une terrasse ensoleill\u00e9e expos\u00e9e plein sud avec jardin privatif, id\u00e9ale pour se d\u00e9tendre ou prendre ses repas en plein air. Cuisine s\u00e9par\u00e9e, spacieuse et lumineuse avec buanderie attenante. Une salle de bain compl\u00e8te avec douche se trouve \u00e9galement \u00e0 ce niveau.\nDeuxi\u00e8me \u00e9tage : quatre chambres (dont une avec acc\u00e8s \u00e0 une terrasse) et une salle de bain compl\u00e8te avec baignoire.\nTroisi\u00e8me \u00e9tage : Suite parentale avec salle de bains attenante et acc\u00e8s \u00e0 une terrasse expos\u00e9e plein sud, id\u00e9ale pour profiter du soleil et de la vue.\nCaract\u00e9ristiques : Fen\u00eatres PVC, carrelage, placards int\u00e9gr\u00e9s.\nL&#039;orientation plein sud garantit une excellente luminosit\u00e9 naturelle tout au long de la journ\u00e9e.\nCe bien fait partie d&#039;une r\u00e9sidence avec piscine commune et jardins bien entretenus, offrant un cadre paisible et relaxant.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">645.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-homer-llafranc-27791\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27284\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">R\u00e9serv\u00e9<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625886-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625887-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625888-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625889-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625890-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625891-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625892-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625893-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625894-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625895-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625896-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625897-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625898-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625899-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625900-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625901-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625902-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625903-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625904-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625905-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625906-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625907-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27284\/625908-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-cal-federal-casa-45-calonge-27284\/\">8 MAISONS NEUVES AVEC JARDIN ET PARKING \u00c0 CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2723<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 toilettes\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 142 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Nouvelle phase en vente \u00e0 Calonge !Suite au succ\u00e8s de la premi\u00e8re phase (7 maisons vendues et en construction, avec livraison en 2026), nous pr\u00e9sentons la troisi\u00e8me phase de cette promotion exclusive \u00e0 Calonge : 8 nouvelles maisons neuves conservant le m\u00eame design et la m\u00eame qualit\u00e9 qui ont suscit\u00e9 tant d&#039;int\u00e9r\u00eat.Chaque maison est pens\u00e9e pour votre confort :4 chambres2 salles de bains compl\u00e8tesJardin privatifPlace de parking incluseDans ce cas, il s&#039;agit du logement d&#039;angle et il dispose de 77.75 m\u00b2 de jardin privatif.Acheter sur plan vous permet de personnaliser votre logement selon vos envies.Pr\u00e9f\u00e9rez-vous les quatre chambres \u00e0 l&#039;\u00e9tage et agrandir tout l&#039;espace de vie au rez-de-chauss\u00e9e ? Deux salles de bains \u00e0 l&#039;\u00e9tage ? Une piscine dans votre jardin ?Tout est possible. Contactez-nous pour plus d&#039;informations et d\u00e9couvrez toutes les options de personnalisation disponibles. La livraison est pr\u00e9vue pour le troisi\u00e8me trimestre 2027, vous laissant le temps n\u00e9cessaire pour organiser votre d\u00e9m\u00e9nagement et adapter votre futur logement.&nbsp;Situ\u00e9 dans un quartier calme et bien desservi, vous aurez la possibilit\u00e9 de profiter d&#039;un environnement naturel et de toutes les commodit\u00e9s dont vous avez besoin \u00e0 port\u00e9e de main.Ne manquez pas l&#039;occasion de vivre dans un lieu unique ! R\u00e9servez d\u00e8s maintenant et commencez \u00e0 imaginer votre avenir dans cette belle maison !\nPromu par : Promociones Molina\nCommercialis\u00e9 par : Corredor Mat\u00f3 &amp; Urbenia Serveis Immobiliaris<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">465.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-cal-federal-casa-45-calonge-27284\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"21561\">\n  <span class=\"n2r__list__item__icon n2r__list__item__icon--withvideo\" title=\"Avec vid\u00e9o\"><i class=\"fas fa-video\"><\/i><\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507749-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507750-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507751-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507752-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507753-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507555-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507754-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507755-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507756-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507558-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507559-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507560-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507561-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507562-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507563-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507564-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507565-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507566-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507567-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507568-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507569-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507570-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507571-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507572-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507573-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507574-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507575-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507576-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507577-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507578-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507757-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507758-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507759-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507760-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507761-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507762-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507763-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507764-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507765-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507766-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507767-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507768-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507769-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507770-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507771-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507772-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507773-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507774-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507775-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21561\/507776-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/img.youtube.com\/vi\/nMOheEX_bVQ\/0.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-ses-falugues-begur-21561\/\">Villa de Luxe avec Vue Panoramique sur la Mer \u00e0 Aiguablava, Begur<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2366<\/div>\n            <div class=\"n2r__list__item__city\">Begur<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"6 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 6<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"8 toilettes\"><i class=\"n2r_toilet\"><\/i> 8<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 1338 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Cette superbe villa individuelle, situ\u00e9e dans l&#039;urbanisation exclusive de Ses Falugues, est une v\u00e9ritable oasis de luxe et de confort. Avec une architecture \u00e9tonnante et un design int\u00e9rieur sophistiqu\u00e9, cette propri\u00e9t\u00e9 offre une exp\u00e9rience de vie in\u00e9gal\u00e9e.Caract\u00e9ristiques exceptionnelles :Espaces spacieux et lumineux : la villa est distribu\u00e9e sur un \u00e9tage, avec de hauts plafonds et de grandes fen\u00eatres qui inondent les espaces de lumi\u00e8re naturelle. Le salon principal, avec sa chemin\u00e9e et son coin lecture, est le c\u0153ur de la maison et offre des vues spectaculaires sur la mer et le jardin.Jardin et piscine priv\u00e9s : entour\u00e9e d&#039;un jardin luxuriant de plus de 4 382 m\u00b2, la villa dispose d&#039;une piscine ext\u00e9rieure de 21x7 m\u00e8tres et d&#039;une piscine int\u00e9rieure. La cour int\u00e9rieure ajoute une touche d&#039;intimit\u00e9 et de tranquillit\u00e9.Suite principale de luxe : la suite principale, d&#039;une superficie de pr\u00e8s de 70 m\u00b2, est un v\u00e9ritable sanctuaire. Elle dispose d&#039;un grand dressing, d&#039;une salle de bains de r\u00eave avec jacuzzi et douche \u00e0 l&#039;italienne, et d&#039;un acc\u00e8s direct \u00e0 la v\u00e9randa et \u00e0 la piscine.Chambres suppl\u00e9mentaires : en plus de la suite principale, la villa dispose de deux chambres doubles avec salle de bains, toutes avec dressing et salle de bains compl\u00e8te.Espaces de loisirs et de d\u00e9tente : la piscine int\u00e9rieure chauff\u00e9e, la salle de sport et le spa offrent des possibilit\u00e9s infinies de d\u00e9tente et de bien-\u00eatre.Technologie et durabilit\u00e9 : la villa dispose d&#039;un syst\u00e8me de s\u00e9curit\u00e9 de pointe, de panneaux solaires, de r\u00e9servoirs d&#039;eau de pluie et d&#039;un syst\u00e8me d&#039;irrigation automatique.Situation privil\u00e9gi\u00e9e : Situ\u00e9e \u00e0 Ses Falugues, l&#039;une des urbanisations les plus exclusives d&#039;Aiguablava, cette villa offre un cadre paisible et priv\u00e9, \u00e0 quelques minutes seulement des plages cristallines et du charmant village de Begur.Un style de vie exclusif :Cette propri\u00e9t\u00e9 est id\u00e9ale pour ceux qui recherchent une maison de luxe dans un cadre naturel privil\u00e9gi\u00e9. Avec ses grands espaces, son design sophistiqu\u00e9 et ses vues panoramiques sur la mer, cette villa offre une exp\u00e9rience de vie unique sur la Costa Brava.Possibilit\u00e9 d&#039;acheter la parcelle adjacente . Renseignez-vous aupr\u00e8s de nous !<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">5.900.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-ses-falugues-begur-21561\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"27015\">\n    <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617614-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617615-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617616-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617617-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617618-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617619-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617620-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617621-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617622-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617623-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617624-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617625-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617626-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27015\/617627-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-ronda-coral-llafranc-27015\/\">Villa dans le prestigieux village de Llafranc avec vue mer et sur les colines.<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2685<\/div>\n      <div class=\"n2r__list__item__turisticreference\">WITH TOURIST LICENSE<\/div>      <div class=\"n2r__list__item__city\">Llafranc<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"4 toilettes\"><i class=\"n2r_toilet\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 296 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Cette villa se trouve au c\u0153ur de la Costa Brava, sur le bel village de LLafranc. Elle a \u00e9t\u00e9 renouvel\u00e9e avec style moderne et accueillant. En utilisant des materiaux de qualit\u00e9 et de design, sol en parquet, double vitrage, robinets modernes, cuisine et salle de bains\u2026.\n\nLa baie de Llafranc se trouve \u00e0 quelques minutes \u00e0 pied, avec sa longe plage de sable fin, bord\u00e9e par une agr\u00e9able promenade qui porte jusqu&#039;au son port nautique. On peut pas oublier son chemin littoral avec merveilleuses vues sur la mer et la c\u00f4te, qui arrive \u00e0 Calella de Palafrugell , un autre petit village des p\u00eacheurs, situ\u00e9 \u00e0 seulement quelques minutes en voiture de LLafranc, qui offre de bels zones de promenade, commerces et restaurants.\n\nCette magnifique propri\u00e9t\u00e9 se compose de 2 niveaux.\n\nAu niveau de la rue une terrasse nous donne la bienvenue depuis laquelle on acc\u00e8de \u00e0 la propri\u00e9t\u00e9, au garage (1 voiture)  et les escaliers ext\u00e9rieurs par lesquels on peut acc\u00e9der au reste de zones ext\u00e9rieures de la propri\u00e9t\u00e9 comme la terrasse de la cuisine ou le jardin avec piscine\n\nLa maison offre un mignon et lumineux hall qui communique avec le garage et les jolies escaliers qui distribuent la plante dans : un espace ouvert comme bureau, toilette, joli et un ample s\u00e9jour-salle \u00e0 manger avec chemin\u00e9e et sortie \u00e0 une splendide terrasse depuis laquelle  on peut jouir  de la vue \u00e0 la mer.\n\n\u00c0 la plante d&#039;en bas s&#039;acc\u00e8de pour 2 escaliers, une pour aller \u00e0 la zone des chambres et l&#039;autre directement \u00e0 la cuisine. La maison a une suite avec armoires encastr\u00e9es et une salle de bains moderne avec douche, 2 chambres doubles, 1 salle de bains\/douche, 1 chambre avec lits superpos\u00e9es et salle de bains\/douche, laquelle a sortie directe au jardin.\n\nLa r\u00e9forme de la cuisine de cette maison a \u00e9t\u00e9 spectaculaire et tr\u00e8s m\u00e9diter au moment de choisir le mobili\u00e8re et les \u00e9lectrom\u00e9nagers, tous modernes, fonctionnelles  et d&#039;haute gamme : frigo am\u00e9ricaine, hotte int\u00e9gr\u00e9 dans la table de cuisson, plan du travail aluminium, design pour le stockage et un vaste coin pour diner pour jouir de cette pi\u00e8ce. Avec des grandes fen\u00eatres pour vivre dans une ambiance naturelle. Sortie \u00e0 une jolie terrasse d\u00e8s on peut acc\u00e9der aux escaliers qui portent \u00e0 la piscine.\n\nExt\u00e9rieures avec joli jardin entourant la piscine et air de repos avec tar\u00eemes en bo\u00eete. \u00c0 ce niveau de la piscine a une terrasse couverte avec cuisine bien am\u00e9nag\u00e9e et salle de bains\/douche.\n\nCette propri\u00e9t\u00e9 a chauffage centrale du gas naturelle. Air conditionnel.\n\nPanneaux solaires.\n\nSa situation est tr\u00e8s calme et id\u00e9ale pour profiter 365 jours de l&#039;ann\u00e9e dans ce fabuleux coin de la Costa Brava.\n\nIl dispose d&#039;une licence touristique et peut obtenir un rendement \u00e9lev\u00e9 en tant qu&#039;h\u00e9bergement touristique.&nbsp;<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">1.490.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-ronda-coral-llafranc-27015\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"21270\">\n    <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496270-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496271-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496272-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496273-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496274-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496275-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496276-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496277-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496278-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496433-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496434-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496435-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496436-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496437-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496438-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496439-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496440-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496441-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496442-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496443-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496444-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496445-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496446-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496447-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496448-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/21270\/496449-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-mas-pere-a-calonge-21270\/\">MAS PERE A - Maison unifamiliale de nouvelle construction avec piscine<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2299<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"5 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 5<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"5 toilettes\"><i class=\"n2r_toilet\"><\/i> 5<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 318 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Profitez d&#039;une maison unifamiliale neuve sp\u00e9cialement con\u00e7ue pour offrir un maximum de confort et de bien-\u00eatre \u00e0 ses habitants. Cette propri\u00e9t\u00e9, situ\u00e9e dans une zone privil\u00e9gi\u00e9e, devient le refuge id\u00e9al pour ceux qui recherchent l&#039;exclusivit\u00e9, la tranquillit\u00e9 et un style de vie connect\u00e9 \u00e0 la nature. Espace et luminosit\u00e9 dans un design moderne\nLa maison, d&#039;une superficie utile totale de 224 m\u00b2, est r\u00e9partie sur trois \u00e9tages. Sa conception et la disposition strat\u00e9gique des marges de recul g\u00e9n\u00e8rent des patios int\u00e9rieurs qui apportent de la lumi\u00e8re naturelle \u00e0 toutes les pi\u00e8ces, cr\u00e9ant une atmosph\u00e8re spacieuse et accueillante.\nSous-sol\nAu sous-sol, nous trouvons un grand garage d&#039;une capacit\u00e9 de deux v\u00e9hicules (38&#039;50 m\u00b2), accessible aussi bien depuis la rue que depuis l&#039;int\u00e9rieur de la maison. Un ascenseur relie le sous-sol au rez-de-chauss\u00e9e, offrant plus de confort et d&#039;accessibilit\u00e9.\nRez-de-chauss\u00e9e\nLe rez-de-chauss\u00e9e a un total de 128 m\u00b2 construits dans lesquels on trouve une grande cuisine ouverte sur le coin repas. Salon  . Une salle de bain de courtoisie et une chambre double spacieuse avec une salle de bain attenante.\nRez-de-chauss\u00e9e\nAu premier \u00e9tage, avec un total de 120 m\u00b2 construits, il y a quatre chambres doubles avec leurs salles de bains correspondantes ainsi qu&#039;un salon spacieux. \nToutes les chambres disposent de grandes fen\u00eatres offrant une vue ext\u00e9rieure et un acc\u00e8s \u00e0 de petits patios priv\u00e9s, cr\u00e9ant un lien unique avec la nature.\nExt\u00e9rieur.La configuration de la maison permet de profiter d&#039;un espace ext\u00e9rieur g\u00e9n\u00e9reux. Depuis le couloir du rez-de-chauss\u00e9e, on acc\u00e8de \u00e0 une grande terrasse avec un porche qui entoure la piscine (24,50 m\u00b2), cr\u00e9ant une oasis parfaite pour la d\u00e9tente et les loisirs en plein air.\nCaract\u00e9ristiques suppl\u00e9mentaires\nLogement \u00e0 faibles \u00e9missions de type Passivhaus, qui garantit une haute efficacit\u00e9 \u00e9nerg\u00e9tique et un confort thermique optimal.\nAscenseur qui relie les trois \u00e9tages de la maison.\nPiscine priv\u00e9e.\nGrands patios int\u00e9rieurs.\nMat\u00e9riaux de haute qualit\u00e9 et finitions luxueuses.\n\u00c9quipement complet de cuisine et de salle de bain.\nGrand terrain avec jardin priv\u00e9.\nEmplacement\nLa maison est situ\u00e9e dans un quartier r\u00e9sidentiel calme et bien desservi, avec un acc\u00e8s facile aux principaux services et zones d&#039;int\u00e9r\u00eat.\nNe manquez pas l&#039;opportunit\u00e9 de vivre dans cette maison exclusive de nouvelle construction. Demandez plus d&#039;informations sans engagement.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">890.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-mas-pere-a-calonge-21270\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27285\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">R\u00e9serv\u00e9<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625909-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625910-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625911-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625912-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625913-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625914-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625915-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625916-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625917-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625918-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625919-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625920-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625921-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625922-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625923-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625924-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625925-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625926-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625927-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625928-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625929-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625930-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27285\/625931-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-cal-federal-casa-44-calonge-27285\/\">8 MAISONS NEUVES AVEC JARDIN ET PARKING \u00c0 CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2722<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 toilettes\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Nouvelle phase en vente \u00e0 Calonge !Suite au succ\u00e8s de la premi\u00e8re phase (7 maisons vendues et en construction, avec livraison en 2026), nous pr\u00e9sentons la troisi\u00e8me phase de cette promotion exclusive \u00e0 Calonge : 8 nouvelles maisons neuves conservant le m\u00eame design et la m\u00eame qualit\u00e9 qui ont suscit\u00e9 tant d&#039;int\u00e9r\u00eat.Chaque maison est pens\u00e9e pour votre confort :4 chambres2 salles de bains compl\u00e8tesJardin privatifPlace de parking incluseAcheter sur plan vous permet de personnaliser votre logement selon vos envies.Pr\u00e9f\u00e9rez-vous les quatre chambres \u00e0 l&#039;\u00e9tage et agrandir tout l&#039;espace de vie au rez-de-chauss\u00e9e ? Deux salles de bains \u00e0 l&#039;\u00e9tage ? Une piscine dans votre jardin ?Tout est possible. Contactez-nous pour plus d&#039;informations et d\u00e9couvrez toutes les options de personnalisation disponibles. La livraison est pr\u00e9vue pour le troisi\u00e8me trimestre 2027, vous laissant le temps n\u00e9cessaire pour organiser votre d\u00e9m\u00e9nagement et adapter votre futur logement.&nbsp;Situ\u00e9 dans un quartier calme et bien desservi, vous aurez la possibilit\u00e9 de profiter d&#039;un environnement naturel et de toutes les commodit\u00e9s dont vous avez besoin \u00e0 port\u00e9e de main.Ne manquez pas l&#039;occasion de vivre dans un lieu unique ! R\u00e9servez d\u00e8s maintenant et commencez \u00e0 imaginer votre avenir dans cette belle maison !\nPromu par : Promociones Molina\nCommercialis\u00e9 par : Corredor Mat\u00f3 &amp; Urbenia Serveis Immobiliaris<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">450.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-cal-federal-casa-44-calonge-27285\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable  n2r__list__item--blocked \" data-id=\"27287\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--blocked\">R\u00e9serv\u00e9<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625955-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625956-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625957-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625958-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625959-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625960-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625961-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625962-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625963-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625964-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625965-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625966-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625967-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625968-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625969-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625970-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625971-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625972-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625973-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625974-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625975-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625976-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27287\/625977-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-cal-federal-casa-42-calonge-27287\/\">8 MAISONS NEUVES AVEC JARDIN ET PARKING \u00c0 CALONGE<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2720<\/div>\n            <div class=\"n2r__list__item__city\">Calonge<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 toilettes\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 140 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Nouvelle phase en vente \u00e0 Calonge !Suite au succ\u00e8s de la premi\u00e8re phase (7 maisons vendues et en construction, avec livraison en 2026), nous pr\u00e9sentons la troisi\u00e8me phase de cette promotion exclusive \u00e0 Calonge : 8 nouvelles maisons neuves conservant le m\u00eame design et la m\u00eame qualit\u00e9 qui ont suscit\u00e9 tant d&#039;int\u00e9r\u00eat.Chaque maison est pens\u00e9e pour votre confort :4 chambres2 salles de bains compl\u00e8tesJardin privatifPlace de parking incluseAcheter sur plan vous permet de personnaliser votre logement selon vos envies.Pr\u00e9f\u00e9rez-vous les quatre chambres \u00e0 l&#039;\u00e9tage et agrandir tout l&#039;espace de vie au rez-de-chauss\u00e9e ? Deux salles de bains \u00e0 l&#039;\u00e9tage ? Une piscine dans votre jardin ?Tout est possible. Contactez-nous pour plus d&#039;informations et d\u00e9couvrez toutes les options de personnalisation disponibles. La livraison est pr\u00e9vue pour le troisi\u00e8me trimestre 2027, vous laissant le temps n\u00e9cessaire pour organiser votre d\u00e9m\u00e9nagement et adapter votre futur logement.&nbsp;Situ\u00e9 dans un quartier calme et bien desservi, vous aurez la possibilit\u00e9 de profiter d&#039;un environnement naturel et de toutes les commodit\u00e9s dont vous avez besoin \u00e0 port\u00e9e de main.Ne manquez pas l&#039;occasion de vivre dans un lieu unique ! R\u00e9servez d\u00e8s maintenant et commencez \u00e0 imaginer votre avenir dans cette belle maison !\nPromu par : Promociones Molina\nCommercialis\u00e9 par : Corredor Mat\u00f3 &amp; Urbenia Serveis Immobiliaris<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">450.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-cal-federal-casa-42-calonge-27287\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"17532\">\n  <span class=\"n2r__list__item__label n2r__list__item__label--offer\">Offre<\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359364-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359365-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359366-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359367-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359368-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359369-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359370-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359371-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359372-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359373-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359374-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359375-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359376-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359377-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/17532\/359378-o-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-sa-rufaca-palamos-17532\/\">SA RUFACA<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M1028<\/div>\n      <div class=\"n2r__list__item__turisticreference\">WITH TOURIST LICENSE<\/div>      <div class=\"n2r__list__item__city\">Palam\u00f3s<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"2 toilettes\"><i class=\"n2r_toilet\"><\/i> 2<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 249 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Occasion unique d&#039;acqu\u00e9rir une fabuleuse maison de ville avec une vue incroyable sur la mer et le yacht club de Palam\u00f3s avec license touristique.Construit \u00e0 l&#039;origine en 1920 et enti\u00e8rement r\u00e9nov\u00e9 en 2000. La propri\u00e9t\u00e9 en question est une maison situ\u00e9e \u00e0 l&#039;acien coeur de la ville de Palam\u00f3s, orient\u00e9e vers l&#039;est, construite sur un terrain de 154 m2 avec une superficie totale construite selon le cadastre, de 249 m2.La maison est r\u00e9partie sur quatre niveaux reli\u00e9s par un escalier int\u00e9rieur ainsi que par un ascenseur. Chacun des \u00e9tages a acc\u00e8s \u00e0 diff\u00e9rentes terrasses d&#039;o\u00f9 vous pourrez profiter d&#039;une vue imprenable sur la mer.Au niveau de la rue on trouve le garage, une salle de bain avec douche, un salon et une cuisine. Chemin\u00e9e. Acc\u00e8s \u00e0 une terrasse d&#039;o\u00f9 on descend jusqu&#039;\u00e0 la piscine (21 m2) et un espace de rangement.Le premier \u00e9tage comprend une grande chambre double avec salle de bains privative et jacuzzi. Coin buanderie. Deux chambres doubles et une salle de bain avec douche.Le deuxi\u00e8me \u00e9tage est distribu\u00e9 un grand salon - salle \u00e0 manger et la cuisine principale.Au troisi\u00e8me \u00e9tage, une salle polyvalente id\u00e9ale pour la transformer en une chambre avec salle de bains privative et acc\u00e8s \u00e0 deux terrasses donnant sur la mer et l&#039;int\u00e9rieur. Chauffage central au gaz de ville. Bo\u00eetiers en aluminium avec double vitrage.&nbsp;<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\"><span class=\"n2r__list__item__price__amount n2r__list__item__price__old\">895.000 \u20ac<\/span> 850.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-sa-rufaca-palamos-17532\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"19139\">\n    <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/494080-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493907-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/494081-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493899-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493901-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415535-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415536-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415539-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415540-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415541-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415542-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415543-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415544-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415545-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415546-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415547-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415549-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415550-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/415551-o-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/494082-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493904-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493905-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493906-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493908-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/493900-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/482939-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/482938-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/482936-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/482935-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/482937-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/494083-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/19139\/494084-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-el-far-12-llafranc-19139\/\">EL FAR de Llafranc - un formidable quartier r\u00e9sidentiel avec des formidables vues.<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M1738<\/div>\n      <div class=\"n2r__list__item__turisticreference\">WITH TOURIST LICENSE<\/div>      <div class=\"n2r__list__item__city\">Llafranc<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"4 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"4 toilettes\"><i class=\"n2r_toilet\"><\/i> 4<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 150 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Mer, Ciel, For\u00eat, Relax, Luxe, Technologie, ... sont quelques-uns des noms qui d\u00e9finissent ce fabuleux quartier r\u00e9sidentiel d&#039;El Far, \u00e0 Llafranc - Costa Brava. Formidable maison famille de style contemporain, situ\u00e9e dans une fabuleuse copropri\u00e9t\u00e9 qui a un court de tennis, une piscine et des jardins. Construit fin 2017, il dispose d&#039;un total de 150 m\u00b2 construits et r\u00e9partis sur trois niveaux. Le hall d&#039;acc\u00e8s m\u00e8ne \u00e0 la cuisine ouverte sur la belle salle \u00e0 manger et le salon d&#039;o\u00f9 l&#039;on sort sur la terrasse d&#039;environ 20 m\u00b2. Salle de bain et buanderie. \u00c0 l&#039;\u00e9tage inf\u00e9rieur, il y a trois chambres doubles et une salle de bain. Sortie sur le jardin. L&#039;\u00e9tage sup\u00e9rieur est occup\u00e9 par une fabuleuse chambre double avec salle de bains privative et acc\u00e8s \u00e0 deux terrasses. La maison est \u00e9quip\u00e9e des derni\u00e8res technologies en mati\u00e8re d&#039;isolation thermique et acoustique, de traitement des eaux pluviales et us\u00e9es, de climatisation \u00e9cologique r\u00e9versible, de panneaux solaires, ... Il dispose de deux places de parking couvertes et pr\u00e9-\u00e9quip\u00e9es pour recharger les voitures \u00e9lectriques.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">825.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-el-far-12-llafranc-19139\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"27558\">\n  <span class=\"n2r__list__item__icon n2r__list__item__icon--withvideo\" title=\"Avec vid\u00e9o\"><i class=\"fas fa-video\"><\/i><\/span>  <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636888-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636889-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636890-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636891-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636892-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636893-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636894-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636895-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636896-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636897-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636935-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636898-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636899-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636900-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636901-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636902-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636903-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636904-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636905-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636906-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636907-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636908-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636909-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636910-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636911-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636912-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636913-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636914-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636915-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636916-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636917-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636918-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636919-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636920-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636921-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636922-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636923-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636924-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636925-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636926-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636927-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636928-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636929-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636930-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636931-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636932-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636933-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27558\/636934-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/img.youtube.com\/vi\/4WEz8LqlCfg\/0.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-medes-pals-27558\/\">Medes, une propri\u00e9t\u00e9 unique pour vivre, partager et investir au bord de la mer<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2734<\/div>\n      <div class=\"n2r__list__item__turisticreference\">WITH TOURISTIC LICENSE<\/div>      <div class=\"n2r__list__item__city\">Pals<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"8 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 8<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"5 toilettes\"><i class=\"n2r_toilet\"><\/i> 5<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 245 m<sup>2<\/sup><\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--pool\" title=\"piscine\"><i class=\"n2r_swimming_pool\"><\/i> <\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">\u00c0 quelques minutes de la plage de Platja del Rac\u00f3, cette propri\u00e9t\u00e9 offre une mani\u00e8re de vivre la Costa Brava dans un cadre alliant intimit\u00e9, g\u00e9n\u00e9rosit\u00e9 des espaces et grande capacit\u00e9 d&#039;accueil, pens\u00e9 pour partager des moments privil\u00e9gi\u00e9s tout au long de l&#039;ann\u00e9e.La maison principale se distingue par sa luminosit\u00e9, ses espaces ouverts et sa connexion naturelle avec l&#039;ext\u00e9rieur. La terrasse avec vue sur la mer et le jardin devient un lieu privil\u00e9gi\u00e9 pour profiter des repas en plein air, des couchers de soleil d&#039;\u00e9t\u00e9 et de la douceur m\u00e9diterran\u00e9enne. La piscine priv\u00e9e, la cour et les diff\u00e9rents espaces ext\u00e9rieurs cr\u00e9ent une atmosph\u00e8re d\u00e9tendue et chaleureuse, propice \u00e0 la d\u00e9connexion. De plus, il dispose d&#039;une zone de stationnement.L&#039;habitation principale dispose de trois chambres (dont une en suite) et de deux salles de bains, avec une distribution confortable et fonctionnelle, id\u00e9ale pour les familles nombreuses ou les s\u00e9jours avec invit\u00e9s. En compl\u00e9ment, la propri\u00e9t\u00e9 comprend une annexe ind\u00e9pendante avec deux chambres et une salle de bains, parfaite pour accueillir jusqu&#039;\u00e0 quatre personnes suppl\u00e9mentaires en toute autonomie et intimit\u00e9.Comme valeur ajout\u00e9e exceptionnelle, la propri\u00e9t\u00e9 dispose \u00e9galement d&#039;un appartement ind\u00e9pendant de trois chambres et deux salles de bains, un espace compl\u00e9mentaire qui \u00e9largit consid\u00e9rablement les possibilit\u00e9s d&#039;usage : accueillir la famille \u00e9largie ou g\u00e9n\u00e9rer un revenu locatif.La propri\u00e9t\u00e9 b\u00e9n\u00e9ficie d&#039;une licence touristique, un atout particuli\u00e8rement attractif pour ceux qui souhaitent conjuguer usage personnel et investissement dans l&#039;un des secteurs les plus recherch\u00e9s du littoral.Une maison pens\u00e9e pour \u00eatre pleinement v\u00e9cue, partag\u00e9e et valoris\u00e9e, dans un environnement o\u00f9 la mer et la tranquillit\u00e9 donnent le rythme de chaque journ\u00e9e.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">750.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-villa-medes-pals-27558\/\">Plus<\/a>\n  <\/div><div class=\"n2r__list__item n2r__clickable   \" data-id=\"27040\">\n    <div class=\"n2r__list__item__gallery n2r__slider\">\n    <div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/623768-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617673-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617674-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617675-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617676-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617677-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617678-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617679-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617680-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617681-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617682-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617683-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617684-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617685-m.jpg\" alt=\"\" title=\"\"><\/div><div class=\"slide-item\"><img data-lazy=\"https:\/\/files.net2rent.com\/pfiles\/43\/27040\/617686-m.jpg\" alt=\"\" title=\"\"><\/div>  <\/div>\n\n  <div class=\"n2r__list__item__info\">\n    <div class=\"n2r__list__item__title\">\n      <h2 class=\"n2r__list__item__name\">\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-aiguafreda-begur-27040\/\">Maison mitoyenne avec vue sur mer \u00e0 vendre sur Begur, Aiguafreda<\/a>\n      <\/h2>\n          <\/div>\n    <div class=\"n2r__list__item__title\">\n      <div class=\"n2r__list__item__reference\">Ref: M2694<\/div>\n            <div class=\"n2r__list__item__city\">Begur<\/div>\n          <\/div>\n    <div class=\"n2r__list__item__features\">\n      <div class=\"n2r__list__item__feature n2r__list__item__feature--rooms\" title=\"3 chambres \u00e0 coucher\"><i class=\"n2r_room\"><\/i> 3<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--bathrooms\" title=\"3 toilettes\"><i class=\"n2r_toilet\"><\/i> 3<\/div><div class=\"n2r__list__item__feature n2r__list__item__feature--property_meters\" title=\"M\u00e8tres de la propri\u00e9t\u00e9\"><i class=\"n2r_property_meters\"><\/i> 162 m<sup>2<\/sup><\/div>    <\/div>\n    <div class=\"n2r__list__item__description\">Bienvenue dans cette magnifique maison r\u00e9cemment r\u00e9nov\u00e9e, offrant une vue spectaculaire sur la mer et une situation privil\u00e9gi\u00e9e \u00e0 seulement 1,5 km de la plage de Sa Tuna et \u00e0 4 km du centre de Begur. Cette propri\u00e9t\u00e9 allie modernit\u00e9, confort et un cadre naturel de r\u00eave, id\u00e9al pour ceux qui recherchent tranquillit\u00e9 et beaut\u00e9 sur la Costa Brava. nnLa maison est con\u00e7ue sur un seul niveau, ce qui la rend tr\u00e8s pratique et accessible pour tous les \u00e2ges. En entrant, vous d\u00e9couvrirez un salon lumineux et accueillant avec de grandes fen\u00eatres et un acc\u00e8s direct \u00e0 une terrasse et un jardin priv\u00e9. Cet espace ext\u00e9rieur est parfait pour profiter du beau temps, organiser des repas en plein air ou simplement se d\u00e9tendre en admirant la vue sur la mer. La cuisine ouverte et la salle \u00e0 manger forment un espace d\u00e9gag\u00e9 et fonctionnel, id\u00e9al pour pr\u00e9parer et partager des repas avec famille et amis. La disposition comprend trois chambres doubles, toutes spacieuses et chaleureuses. Deux de ces chambres sont en suite avec salle de bain priv\u00e9e, offrant un haut niveau de confort et d&#039;intimit\u00e9, tandis que la troisi\u00e8me chambre partage une salle de bain compl\u00e8te, parfaitement pens\u00e9e pour les invit\u00e9s ou d&#039;autres membres de la famille. De plus, la propri\u00e9t\u00e9 dispose d&#039;un garage pour un v\u00e9hicule ainsi que d&#039;un espace de stationnement ext\u00e9rieur pouvant accueillir plusieurs voitures, assurant tranquillit\u00e9 et commodit\u00e9 au quotidien. nnEn r\u00e9sum\u00e9, cette maison r\u00e9nov\u00e9e est une opportunit\u00e9 unique d&#039;acqu\u00e9rir une r\u00e9sidence avec vue sur la mer, dans un environnement calme mais bien connect\u00e9, id\u00e9ale comme r\u00e9sidence secondaire ou principale. La combinaison de modernit\u00e9, d&#039;espaces ouverts et sa situation privil\u00e9gi\u00e9e en font une option qui ne vous laissera pas indiff\u00e9rent.<\/div>\n    <div class=\"n2r__list__item__footer\">\n      <div class=\"n2r__list__item__price\">795.000 \u20ac<\/div>    <\/div>\n  <\/div>\n  <a class=\"n2r__list__item__link\" href=\"https:\/\/www.corredormato.com\/fr\/vendre\/vente-maison-mitoyenne-aiguafreda-begur-27040\/\">Plus<\/a>\n  <\/div>    <\/div>\n    <div class=\"n2r__list__map \">\n  <div class=\"n2r__sticky\">\n    <div id=\"n2r__list__map__googlemaps\" class=\"n2r__googlemaps\" data-n2r-scrollwheel=\"0\" data-n2r-markerclustererimage=\"https:\/\/www.corredormato.com\/wp-content\/plugins\/net2rent-wp-plugin\/\/assets\/js\/googlemaps\/images\/m\"   data-n2r-markerimage=\"https:\/\/www.corredormato.com\/wp-content\/plugins\/net2rent-wp-plugin\/\/assets\/images\/map_position.png\" data-n2r-markers=\"[{&quot;id&quot;:&quot;27683&quot;,&quot;latitude&quot;:41.97522,&quot;longitude&quot;:3.206572,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-es-raco-begur-27683\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27683\\\/642438-m.jpg&quot;,&quot;title&quot;:&quot;Magnifique maison avec piscine et une vue magnifique sur la mer, \\u00e0 seulement 500 m\\u00e8tres de la plage&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E1.450.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27791&quot;,&quot;latitude&quot;:41.893215,&quot;longitude&quot;:3.187263,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-maison-mitoyenne-homer-llafranc-27791\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27791\\\/645408-m.jpg&quot;,&quot;title&quot;:&quot;Maison mitoyenne \\u00e0 Llafranc, \\u00e0 seulement 500 m\\u00e8tres de la plage&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;5 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 5\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E645.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27284&quot;,&quot;latitude&quot;:41.859844,&quot;longitude&quot;:3.084614,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-maison-mitoyenne-cal-federal-casa-45-calonge-27284\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27284\\\/625886-m.jpg&quot;,&quot;title&quot;:&quot;8 MAISONS NEUVES AVEC JARDIN ET PARKING \\u00c0 CALONGE&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E465.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;21561&quot;,&quot;latitude&quot;:41.935116,&quot;longitude&quot;:3.207767,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-ses-falugues-begur-21561\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/21561\\\/507749-m.jpg&quot;,&quot;title&quot;:&quot;Villa de Luxe avec Vue Panoramique sur la Mer \\u00e0 Aiguablava, Begur&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;6 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 6\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E5.900.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27015&quot;,&quot;latitude&quot;:41.897125,&quot;longitude&quot;:3.187823,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-ronda-coral-llafranc-27015\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27015\\\/617614-m.jpg&quot;,&quot;title&quot;:&quot;Villa dans le prestigieux village de Llafranc avec vue mer et sur les colines.&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E1.490.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;21270&quot;,&quot;latitude&quot;:41.884682,&quot;longitude&quot;:3.073478,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-mas-pere-a-calonge-21270\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/21270\\\/496270-m.jpg&quot;,&quot;title&quot;:&quot;MAS PERE A - Maison unifamiliale de nouvelle construction avec piscine&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;5 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 5\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E890.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27285&quot;,&quot;latitude&quot;:41.859844,&quot;longitude&quot;:3.084614,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-maison-mitoyenne-cal-federal-casa-44-calonge-27285\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27285\\\/625909-m.jpg&quot;,&quot;title&quot;:&quot;8 MAISONS NEUVES AVEC JARDIN ET PARKING \\u00c0 CALONGE&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E450.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27287&quot;,&quot;latitude&quot;:41.859844,&quot;longitude&quot;:3.084614,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-maison-mitoyenne-cal-federal-casa-42-calonge-27287\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27287\\\/625955-m.jpg&quot;,&quot;title&quot;:&quot;8 MAISONS NEUVES AVEC JARDIN ET PARKING \\u00c0 CALONGE&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E450.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;17532&quot;,&quot;latitude&quot;:41.845032,&quot;longitude&quot;:3.13131,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-sa-rufaca-palamos-17532\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/17532\\\/359364-o-m.jpg&quot;,&quot;title&quot;:&quot;SA RUFACA&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;8 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 8\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E\\u003Cspan class=\\&quot;n2r__list__item__price__amount n2r__list__item__price__old\\&quot;\\u003E895.000 \\u20ac\\u003C\\\/span\\u003E 850.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;19139&quot;,&quot;latitude&quot;:41.90004,&quot;longitude&quot;:3.20088,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-el-far-12-llafranc-19139\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/19139\\\/494080-m.jpg&quot;,&quot;title&quot;:&quot;EL FAR de Llafranc - un formidable quartier r\\u00e9sidentiel avec des formidables vues.&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;4 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 4\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E825.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27558&quot;,&quot;latitude&quot;:41.979923,&quot;longitude&quot;:3.201973,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-villa-medes-pals-27558\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27558\\\/636888-m.jpg&quot;,&quot;title&quot;:&quot;Medes, une propri\\u00e9t\\u00e9 unique pour vivre, partager et investir au bord de la mer&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;8 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 8\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E750.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}},{&quot;id&quot;:&quot;27040&quot;,&quot;latitude&quot;:41.967167,&quot;longitude&quot;:3.225311,&quot;link&quot;:&quot;https:\\\/\\\/www.corredormato.com\\\/fr\\\/vendre\\\/vente-maison-mitoyenne-aiguafreda-begur-27040\\\/&quot;,&quot;infoWindow&quot;:{&quot;image&quot;:&quot;https:\\\/\\\/files.net2rent.com\\\/pfiles\\\/43\\\/27040\\\/623768-m.jpg&quot;,&quot;title&quot;:&quot;Maison mitoyenne avec vue sur mer \\u00e0 vendre sur Begur, Aiguafreda&quot;,&quot;description&quot;:&quot;\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--rooms\\&quot; title=\\&quot;3 chambres \\u00e0 coucher\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_room\\&quot;\\u003E\\u003C\\\/i\\u003E 3\\u003C\\\/div\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__feature n2r__list__item__feature--capacity\\&quot; title=\\&quot;0 pax\\&quot;\\u003E\\u003Ci class=\\&quot;n2r_people\\&quot;\\u003E\\u003C\\\/i\\u003E 0\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E\\u003Cdiv\\u003E\\u003Cdiv class=\\&quot;n2r__list__item__price\\&quot;\\u003E795.000 \\u20ac\\u003C\\\/div\\u003E\\u003C\\\/div\\u003E&quot;}}]\" data-n2r-lodgingsurl=\"https:\/\/www.corredormato.com\/wp-json\/n2r\/v1\/lodgings\/list\" ><\/div>\n  <\/div>\n\n<\/div>  <\/div>\n  <div class=\"n2r__pagination\">\n  <div class=\"n2r__pagination__summary\">\n    59 R\u00e9sultats    -\n    Page 1 sur 5  <\/div>\n  <div class=\"separator\"><\/div>\n      <div class=\"n2r__pagination__links\">\n      <a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/\" class=\"active\" data-page=\"1\">1<\/a><a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/pg-2\/\" class=\"\" data-page=\"2\">2<\/a><span>...<\/span><a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/pg-5\/\" class=\"\" data-page=\"5\">5<\/a>        <a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/pg-2\/\" data-page=\"2\" class=\"n2r__pagination__links__icon\">&rsaquo;<\/a>\n        <a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/pg-5\/\" data-page=\"5\" class=\"n2r__pagination__links__icon\">&raquo;<\/a>\n          <\/div>\n      <div class=\"n2r__pagination__itemsperpage\">\n      <form method=\"GET\" action=\"\">\n                <label for=\"items_per_page\">Par page<\/label>\n        <select class=\"n2r__select\" id=\"items_per_page\" name=\"items\" onchange=\"this.form.submit()\">\n          <option value=\"12\"  selected='selected'>12<\/option><option value=\"24\" >24<\/option><option value=\"48\" >48<\/option>        <\/select>\n      <\/form>\n    <\/div>\n  <\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8cdd59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8cdd59\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66dfed6\" data-id=\"66dfed6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c258f4 elementor-widget elementor-widget-text-editor\" data-id=\"0c258f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Trouvez votre maison sur la Costa Brava et vivez le style de vie m\u00e9diterran\u00e9en<\/h2>\n<p><span style=\"font-weight: 400;\">D\u00e9couvrez un monde de possibilit\u00e9s avec nos maisons \u00e0 vendre sur la Costa Brava. Ce coin du paradis m\u00e9diterran\u00e9en offre une grande vari\u00e9t\u00e9 de propri\u00e9t\u00e9s pour r\u00e9pondre \u00e0 tous les styles de vie et \u00e0 tous les budgets. Des appartements charmants avec des vues panoramiques aux impressionnantes villas avec acc\u00e8s \u00e0 la plage, vous trouverez votre maison id\u00e9ale sur la Costa Brava. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Notre s\u00e9lection de maisons \u00e0 vendre sur la Costa Brava pr\u00e9sente des caract\u00e9ristiques uniques telles que des designs modernes, de grands espaces ext\u00e9rieurs, des piscines priv\u00e9es et la proximit\u00e9 de plages aux eaux cristallines. Quelles que soient vos pr\u00e9f\u00e9rences, nous sommes l\u00e0 pour vous aider \u00e0 trouver la propri\u00e9t\u00e9 de vos r\u00eaves. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vivre sur la Costa Brava, c&#8217;est profiter d&#8217;un style de vie d\u00e9tendu et ensoleill\u00e9, entour\u00e9 de la beaut\u00e9 naturelle de la c\u00f4te et de la riche culture locale. Avec un climat m\u00e9diterran\u00e9en, vous pouvez profiter d&#8217;activit\u00e9s de plein air toute l&#8217;ann\u00e9e, des promenades relaxantes sur la plage aux sports nautiques passionnants. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ne manquez pas cette opportunit\u00e9 d&#8217;investir dans une propri\u00e9t\u00e9 sur la Costa Brava. Contactez-nous aujourd&#8217;hui pour obtenir des conseils personnalis\u00e9s et faire le premier pas vers votre nouvelle maison dans ce paradis c\u00f4tier. Notre \u00e9quipe d&#8217;experts est l\u00e0 pour vous aider \u00e0 trouver la maison \u00e0 vendre sur la Costa Brava qui correspond parfaitement \u00e0 vos besoins et d\u00e9sirs.<\/span><\/p>\n<h2>Quels types de maisons \u00e0 vendre pouvez-vous trouver sur la Costa Brava ?<\/h2>\n<p><span style=\"font-weight: 400;\">\u00a0Sur la Costa Brava, vous trouverez une large et diverse s\u00e9lection de maisons \u00e0 vendre qui couvrent une large gamme de styles et de caract\u00e9ristiques pour r\u00e9pondre aux go\u00fbts et aux besoins de nombreux acheteurs. Voici quelques-unes des options de maisons \u00e0 vendre que vous pouvez trouver dans cette belle r\u00e9gion c\u00f4ti\u00e8re : des villas de luxe, la Costa Brava est connue pour ses villas de luxe offrant de grands espaces, des piscines priv\u00e9es et de magnifiques jardins ; des masias, pour ceux qui recherchent un refuge paisible, situ\u00e9es dans les villages pittoresques de la Costa Brava, elles sont une option charmante ; des maisons de ville et des duplex, des maisons de ville et des duplex offrent une option de logement plus compacte mais avec des commodit\u00e9s telles que des jardins ou des patios, elles sont id\u00e9ales pour les familles ; des propri\u00e9t\u00e9s neuves, si vous \u00eates int\u00e9ress\u00e9 par un projet de construction neuve, d\u00e9couvrez les projets en d\u00e9veloppement disponibles sur la Costa Brava ; des maisons avec un acc\u00e8s direct \u00e0 la plage, pour les amoureux de la mer, certaines propri\u00e9t\u00e9s ont un acc\u00e8s direct aux plages ou aux criques, ce qui vous permet de profiter de la c\u00f4te de mani\u00e8re unique ; des maisons avec vue panoramique, la topographie de la Costa Brava offre souvent des opportunit\u00e9s pour des maisons en hauteur avec des vues panoramiques sur la mer ou la campagne environnante. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En r\u00e9sum\u00e9, sur la Costa Brava, vous pouvez trouver une grande vari\u00e9t\u00e9 de maisons \u00e0 vendre, allant de luxueuses propri\u00e9t\u00e9s en bord de mer \u00e0 des masias pleines de charme. Quel que soit votre style de vie et vos pr\u00e9f\u00e9rences, cette r\u00e9gion a quelque chose de sp\u00e9cial \u00e0 offrir aux acheteurs de biens immobiliers.<\/span><\/p>\n<h2>D\u00e9couvrez les meilleures zones de la Costa Brava pour trouver de magnifiques maisons \u00e0 vendre<\/h2>\n<p><span style=\"font-weight: 400;\">Vous cherchez des maisons \u00e0 vendre sur la Costa Brava ? Explorez une large s\u00e9lection de propri\u00e9t\u00e9s \u00e0 vendre sur la Costa Brava ! Cette belle r\u00e9gion offre une vari\u00e9t\u00e9 d&#8217;options pour les acheteurs de maisons qui veulent profiter d&#8217;un style de vie m\u00e9diterran\u00e9en unique. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous trouverez des villes c\u00f4ti\u00e8res charmantes telles que \u00a0<span style=\"text-decoration: underline;\"><b>Tamariu<\/b><\/span>,\u00a0<span style=\"text-decoration: underline;\">Calella de Palafrugell<\/span> et <span style=\"text-decoration: underline;\">Llafranc<\/span>,, connues pour leurs plages de sable blanc et leur ambiance d\u00e9tendue. Begur, avec ses vues imprenables sur la mer, est parfait pour ceux qui recherchent un cadre paisible et pittoresque. <span style=\"text-decoration: underline;\">Palam\u00f3s<\/span>, avec son port de p\u00eache actif, offre une exp\u00e9rience c\u00f4ti\u00e8re authentique.<\/span><\/p>\n<p>Vous pouvez \u00e9galement envisager d&#8217;acheter une maison \u00e0 <span style=\"text-decoration: underline;\"><span style=\"font-weight: 400;\">Platja d\u00b4Aro<\/span><\/span><span style=\"font-weight: 400;\"> ou \u00e0 <\/span><span style=\"text-decoration: underline;\"><span style=\"font-weight: 400;\">Sant Feliu de Gu\u00edxols<\/span><\/span><span style=\"font-weight: 400;\">,\u00a0<\/span> connues pour leurs commodit\u00e9s et leurs activit\u00e9s de loisirs et offrant une large gamme de services.<\/p>\n<p>Ce ne sont l\u00e0 que quelques-unes des zones o\u00f9 vous pouvez trouver des maisons \u00e0 vendre sur la Costa Brava. Avec sa beaut\u00e9 naturelle, son climat m\u00e9diterran\u00e9en et sa grande vari\u00e9t\u00e9 de propri\u00e9t\u00e9s disponibles, cette r\u00e9gion est un endroit merveilleux pour trouver votre nouvelle maison en bord de mer.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f88c7cf elementor-widget elementor-widget-shortcode\" data-id=\"f88c7cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><style>.wp-show-posts-columns#wpsp-8455 {margin-left: -2em; }.wp-show-posts-columns#wpsp-8455 .wp-show-posts-inner {margin: 0 0 2em 2em; }<\/style><section id=\"wpsp-8455\" class=\" wp-show-posts-columns wp-show-posts\" style=\"\"><article class=\" wp-show-posts-single post-8352 page type-page status-publish has-post-thumbnail hentry wpsp-col-4\" itemtype=\"http:\/\/schema.org\/CreativeWork\" itemscope><div class=\"wp-show-posts-inner\" style=\"\">\t\t\t\t\t\t<header class=\"wp-show-posts-entry-header\">\n\t\t\t\t\t\t\t<h3 class=\"wp-show-posts-entry-title\" itemprop=\"headline\"><a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/vue-sur-la-mer\/\" rel=\"bookmark\">Maisons \u00e0 vendre sur la Costa Brava avec vue sur la mer<\/a><\/h3>\t\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t\t\t\t<div class=\"wp-show-posts-image  wpsp-image-center \">\n\t\t\t<a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/vue-sur-la-mer\/\"  title=\"Maisons \u00e0 vendre sur la Costa Brava avec vue sur la mer\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"887\" src=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-4.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Cases en venda a la Costa Brava amb vistes al mar\" itemprop=\"image\" srcset=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-4.png 1280w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-4-300x208.png 300w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-4-1024x710.png 1024w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-4-768x532.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a>\t\t<\/div>\n\t\t<\/div><!-- wp-show-posts-inner --><\/article><article class=\" wp-show-posts-single post-8341 page type-page status-publish has-post-thumbnail hentry wpsp-col-4\" itemtype=\"http:\/\/schema.org\/CreativeWork\" itemscope><div class=\"wp-show-posts-inner\" style=\"\">\t\t\t\t\t\t<header class=\"wp-show-posts-entry-header\">\n\t\t\t\t\t\t\t<h3 class=\"wp-show-posts-entry-title\" itemprop=\"headline\"><a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/\" rel=\"bookmark\">Maisons \u00e0 vendre sur la Costa Brava<\/a><\/h3>\t\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t\t\t\t<div class=\"wp-show-posts-image  wpsp-image-center \">\n\t\t\t<a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/\"  title=\"Maisons \u00e0 vendre sur la Costa Brava\"><img decoding=\"async\" width=\"1280\" height=\"887\" src=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Cases en venda a la Costa Brava\" itemprop=\"image\" srcset=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava.jpg 1280w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava-300x208.jpg 300w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava-1024x710.jpg 1024w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava-768x532.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a>\t\t<\/div>\n\t\t<\/div><!-- wp-show-posts-inner --><\/article><article class=\" wp-show-posts-single post-8334 page type-page status-publish has-post-thumbnail hentry wpsp-col-4\" itemtype=\"http:\/\/schema.org\/CreativeWork\" itemscope><div class=\"wp-show-posts-inner\" style=\"\">\t\t\t\t\t\t<header class=\"wp-show-posts-entry-header\">\n\t\t\t\t\t\t\t<h3 class=\"wp-show-posts-entry-title\" itemprop=\"headline\"><a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/luxe\/\" rel=\"bookmark\">Maisons de luxe sur la Costa Brava<\/a><\/h3>\t\t\t\t\t\t<\/header><!-- .entry-header -->\n\t\t\t\t\t\t\t<div class=\"wp-show-posts-image  wpsp-image-center \">\n\t\t\t<a href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/luxe\/\"  title=\"Maisons de luxe sur la Costa Brava\"><img decoding=\"async\" width=\"1280\" height=\"887\" src=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-3.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" itemprop=\"image\" srcset=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-3.png 1280w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-3-300x208.png 300w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-3-1024x710.png 1024w, https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/FOTOS-IMATGES-PREVIEW-3-768x532.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a>\t\t<\/div>\n\t\t<\/div><!-- wp-show-posts-inner --><\/article><div class=\"wpsp-clear\"><\/div><\/section><!-- .wp-show-posts --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Trouvez votre maison sur la Costa Brava et vivez le style de vie m\u00e9diterran\u00e9en D\u00e9couvrez un monde de possibilit\u00e9s avec nos maisons \u00e0 vendre sur la Costa Brava. Ce coin du paradis m\u00e9diterran\u00e9en offre une grande vari\u00e9t\u00e9 de propri\u00e9t\u00e9s pour r\u00e9pondre \u00e0 tous les styles de vie et \u00e0 tous les budgets. Des appartements charmants [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8464,"parent":4509,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8341","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corredor Mat\u00f3 Real Estate \u00b7 Houses for sale on the Costa Brava<\/title>\n<meta name=\"description\" content=\"From 1060 we offer our services on the Costa Brava to help you find your future home, contact us.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corredor Mat\u00f3 Real Estate \u00b7 Houses for sale on the Costa Brava\" \/>\n<meta property=\"og:description\" content=\"From 1060 we offer our services on the Costa Brava to help you find your future home, contact us.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/\" \/>\n<meta property=\"og:site_name\" content=\"Corredor Mat\u00f3 Real Estate &amp; Property Management\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-29T15:05:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/\",\"name\":\"Corredor Mat\u00f3 Real Estate \u00b7 Houses for sale on the Costa Brava\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.corredormato.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/casas-costabrava.jpg\",\"datePublished\":\"2023-10-02T09:11:52+00:00\",\"dateModified\":\"2024-02-29T15:05:55+00:00\",\"description\":\"From 1060 we offer our services on the Costa Brava to help you find your future home, contact us.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/vente-costa-brava\\\/maisons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vente Costa Brava\",\"item\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/venda-costa-brava\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maisons \u00e0 vendre sur la Costa Brava\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/\",\"name\":\"Corredor Mat\u00f3 Real Estate &amp; Property Management\",\"description\":\"Real Estate &amp; Property Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/#organization\"},\"alternateName\":\"Corredor Mat\u00f3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.corredormato.com\\\/resultats-de-cerca-lloguer\\\/?search_text={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/#organization\",\"name\":\"Corredor Mat\u00f3 | Real Estate & Property Management\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.corredormato.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.corredormato.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.png\",\"width\":970,\"height\":225,\"caption\":\"Corredor Mat\u00f3 | Real Estate & Property Management\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corredormato.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corredor Mat\u00f3 Real Estate \u00b7 Houses for sale on the Costa Brava","description":"From 1060 we offer our services on the Costa Brava to help you find your future home, contact us.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/","og_locale":"fr_FR","og_type":"article","og_title":"Corredor Mat\u00f3 Real Estate \u00b7 Houses for sale on the Costa Brava","og_description":"From 1060 we offer our services on the Costa Brava to help you find your future home, contact us.","og_url":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/","og_site_name":"Corredor Mat\u00f3 Real Estate &amp; Property Management","article_modified_time":"2024-02-29T15:05:55+00:00","og_image":[{"width":1280,"height":887,"url":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/","url":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/","name":"Corredor Mat\u00f3 Real Estate \u00b7 Houses for sale on the Costa Brava","isPartOf":{"@id":"https:\/\/www.corredormato.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/#primaryimage"},"image":{"@id":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/#primaryimage"},"thumbnailUrl":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2023\/10\/casas-costabrava.jpg","datePublished":"2023-10-02T09:11:52+00:00","dateModified":"2024-02-29T15:05:55+00:00","description":"From 1060 we offer our services on the Costa Brava to help you find your future home, contact us.","breadcrumb":{"@id":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.corredormato.com\/fr\/vente-costa-brava\/maisons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.corredormato.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Vente Costa Brava","item":"https:\/\/www.corredormato.com\/fr\/venda-costa-brava\/"},{"@type":"ListItem","position":3,"name":"Maisons \u00e0 vendre sur la Costa Brava"}]},{"@type":"WebSite","@id":"https:\/\/www.corredormato.com\/fr\/#website","url":"https:\/\/www.corredormato.com\/fr\/","name":"Corredor Mat\u00f3 Real Estate &amp; Property Management","description":"Real Estate &amp; Property Management","publisher":{"@id":"https:\/\/www.corredormato.com\/fr\/#organization"},"alternateName":"Corredor Mat\u00f3","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.corredormato.com\/resultats-de-cerca-lloguer\/?search_text={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.corredormato.com\/fr\/#organization","name":"Corredor Mat\u00f3 | Real Estate & Property Management","url":"https:\/\/www.corredormato.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.corredormato.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2021\/04\/logo.png","contentUrl":"https:\/\/www.corredormato.com\/wp-content\/uploads\/2021\/04\/logo.png","width":970,"height":225,"caption":"Corredor Mat\u00f3 | Real Estate & Property Management"},"image":{"@id":"https:\/\/www.corredormato.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/pages\/8341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/comments?post=8341"}],"version-history":[{"count":1,"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/pages\/8341\/revisions"}],"predecessor-version":[{"id":15581,"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/pages\/8341\/revisions\/15581"}],"up":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/pages\/4509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/media\/8464"}],"wp:attachment":[{"href":"https:\/\/www.corredormato.com\/fr\/wp-json\/wp\/v2\/media?parent=8341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}